{"id":23,"date":"2024-02-02T07:31:48","date_gmt":"2024-02-02T07:31:48","guid":{"rendered":"https:\/\/petrerjove.com\/?post_type=sala&#038;p=23"},"modified":"2024-05-03T08:14:42","modified_gmt":"2024-05-03T06:14:42","slug":"sala-polivalente","status":"publish","type":"sala","link":"https:\/\/petrerjove.com\/ca\/sala\/sala-polivalente\/","title":{"rendered":"Sala Polivalente de Petrer Jove &#8211; Lunes a Viernes"},"content":{"rendered":"\n<p>Calle Ortega y Gasset, N\u00ba 26 de Petrer<\/p>\n","protected":false},"template":"","class_list":["post-23","sala","type-sala","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sala Polivalente de Petrer Jove - Lunes a Viernes - Petrer Jove<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/petrerjove.com\/ca\/sala\/sala-polivalente\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sala Polivalente de Petrer Jove - Lunes a Viernes - Petrer Jove\" \/>\n<meta property=\"og:description\" content=\"Calle Ortega y Gasset, N\u00ba 26 de Petrer\" \/>\n<meta property=\"og:url\" content=\"https:\/\/petrerjove.com\/ca\/sala\/sala-polivalente\/\" \/>\n<meta property=\"og:site_name\" content=\"Petrer Jove\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/petrerjoven\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-03T06:14:42+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/petrerjove.com\\\/ca\\\/sala\\\/sala-polivalente\\\/\",\"url\":\"https:\\\/\\\/petrerjove.com\\\/ca\\\/sala\\\/sala-polivalente\\\/\",\"name\":\"Sala Polivalente de Petrer Jove - Lunes a Viernes - Petrer Jove\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/petrerjove.com\\\/ca\\\/#website\"},\"datePublished\":\"2024-02-02T07:31:48+00:00\",\"dateModified\":\"2024-05-03T06:14:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/petrerjove.com\\\/ca\\\/sala\\\/sala-polivalente\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/petrerjove.com\\\/ca\\\/sala\\\/sala-polivalente\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/petrerjove.com\\\/ca\\\/sala\\\/sala-polivalente\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/petrerjove.com\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sala Polivalente de Petrer Jove &#8211; Lunes a Viernes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/petrerjove.com\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/petrerjove.com\\\/ca\\\/\",\"name\":\"Petrer Jove\",\"description\":\"Concejal\u00eda de Infancia y Juventud de Petrer\",\"publisher\":{\"@id\":\"https:\\\/\\\/petrerjove.com\\\/ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/petrerjove.com\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/petrerjove.com\\\/ca\\\/#organization\",\"name\":\"Concejal\u00eda de Juventud de Petrer\",\"url\":\"https:\\\/\\\/petrerjove.com\\\/ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/petrerjove.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/petrerjove.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/petrerjove_horizontal.svg\",\"contentUrl\":\"https:\\\/\\\/petrerjove.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/petrerjove_horizontal.svg\",\"width\":200,\"height\":70,\"caption\":\"Concejal\u00eda de Juventud de Petrer\"},\"image\":{\"@id\":\"https:\\\/\\\/petrerjove.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/petrerjoven\\\/\",\"https:\\\/\\\/www.instagram.com\\\/petrerjove\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sala Polivalente de Petrer Jove - Lunes a Viernes - Petrer Jove","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/petrerjove.com\/ca\/sala\/sala-polivalente\/","og_locale":"ca_ES","og_type":"article","og_title":"Sala Polivalente de Petrer Jove - Lunes a Viernes - Petrer Jove","og_description":"Calle Ortega y Gasset, N\u00ba 26 de Petrer","og_url":"https:\/\/petrerjove.com\/ca\/sala\/sala-polivalente\/","og_site_name":"Petrer Jove","article_publisher":"https:\/\/www.facebook.com\/petrerjoven\/","article_modified_time":"2024-05-03T06:14:42+00:00","twitter_card":"summary_large_image","twitter_misc":{"Temps estimat de lectura":"1 minut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/petrerjove.com\/ca\/sala\/sala-polivalente\/","url":"https:\/\/petrerjove.com\/ca\/sala\/sala-polivalente\/","name":"Sala Polivalente de Petrer Jove - Lunes a Viernes - Petrer Jove","isPartOf":{"@id":"https:\/\/petrerjove.com\/ca\/#website"},"datePublished":"2024-02-02T07:31:48+00:00","dateModified":"2024-05-03T06:14:42+00:00","breadcrumb":{"@id":"https:\/\/petrerjove.com\/ca\/sala\/sala-polivalente\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/petrerjove.com\/ca\/sala\/sala-polivalente\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/petrerjove.com\/ca\/sala\/sala-polivalente\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/petrerjove.com\/ca\/"},{"@type":"ListItem","position":2,"name":"Sala Polivalente de Petrer Jove &#8211; Lunes a Viernes"}]},{"@type":"WebSite","@id":"https:\/\/petrerjove.com\/ca\/#website","url":"https:\/\/petrerjove.com\/ca\/","name":"Petrer Jove","description":"Concejal\u00eda de Infancia y Juventud de Petrer","publisher":{"@id":"https:\/\/petrerjove.com\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/petrerjove.com\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/petrerjove.com\/ca\/#organization","name":"Concejal\u00eda de Juventud de Petrer","url":"https:\/\/petrerjove.com\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/petrerjove.com\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/petrerjove.com\/wp-content\/uploads\/2024\/02\/petrerjove_horizontal.svg","contentUrl":"https:\/\/petrerjove.com\/wp-content\/uploads\/2024\/02\/petrerjove_horizontal.svg","width":200,"height":70,"caption":"Concejal\u00eda de Juventud de Petrer"},"image":{"@id":"https:\/\/petrerjove.com\/ca\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/petrerjoven\/","https:\/\/www.instagram.com\/petrerjove\/"]}]}},"_links":{"self":[{"href":"https:\/\/petrerjove.com\/ca\/wp-json\/wp\/v2\/sala\/23","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/petrerjove.com\/ca\/wp-json\/wp\/v2\/sala"}],"about":[{"href":"https:\/\/petrerjove.com\/ca\/wp-json\/wp\/v2\/types\/sala"}],"wp:attachment":[{"href":"https:\/\/petrerjove.com\/ca\/wp-json\/wp\/v2\/media?parent=23"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}